{"id":61829,"date":"2020-12-14T08:02:31","date_gmt":"2020-12-14T07:02:31","guid":{"rendered":"https:\/\/ew-nutrition.com\/?p=61829"},"modified":"2022-09-20T09:22:19","modified_gmt":"2022-09-20T07:22:19","slug":"are-endotoxins-behind-your-low-livestock-productivity","status":"publish","type":"post","link":"https:\/\/ew-nutrition.com\/de\/are-endotoxins-behind-your-low-livestock-productivity\/","title":{"rendered":"Stehen Endotoxine hinter Ihrer geringen Tierproduktivit\u00e4t?"},"content":{"rendered":"<div class=\"intro\" style=\"text-align: justify;\">\n<p><span style=\"color: #808080; font-size: 10pt;\">Erfahren Sie <a href=\"\/de\/endotoxin-management\/\">hier<\/a> mehr \u00fcber Endotoxine<\/span><\/p>\n<p><strong>Machen Stresssituationen Ihre Tiere krank oder verschlimmert sich eine Krankheit nach Antibiotikabehandlung? Endotoxine k\u00f6nnten die Ursache sein!<\/strong><\/p>\n<p><img decoding=\"async\" class=\"alignnone wp-image-56875\" src=\"https:\/\/ew-nutrition.com\/wp-content\/uploads\/articles\/e.coli-shutterstock_133011722-300x214.jpg\" alt=\"\" width=\"1200\" height=\"854\" srcset=\"https:\/\/ew-nutrition.com\/wp-content\/uploads\/articles\/e.coli-shutterstock_133011722-300x214.jpg 300w, https:\/\/ew-nutrition.com\/wp-content\/uploads\/articles\/e.coli-shutterstock_133011722-2023x1440.jpg 2023w, https:\/\/ew-nutrition.com\/wp-content\/uploads\/articles\/e.coli-shutterstock_133011722-150x107.jpg 150w, https:\/\/ew-nutrition.com\/wp-content\/uploads\/articles\/e.coli-shutterstock_133011722-120x85.jpg 120w, https:\/\/ew-nutrition.com\/wp-content\/uploads\/articles\/e.coli-shutterstock_133011722-36x26.jpg 36w, https:\/\/ew-nutrition.com\/wp-content\/uploads\/articles\/e.coli-shutterstock_133011722-225x160.jpg 225w, https:\/\/ew-nutrition.com\/wp-content\/uploads\/articles\/e.coli-shutterstock_133011722-80x57.jpg 80w, https:\/\/ew-nutrition.com\/wp-content\/uploads\/articles\/e.coli-shutterstock_133011722-48x34.jpg 48w, https:\/\/ew-nutrition.com\/wp-content\/uploads\/articles\/e.coli-shutterstock_133011722-64x46.jpg 64w, https:\/\/ew-nutrition.com\/wp-content\/uploads\/articles\/e.coli-shutterstock_133011722-28x20.jpg 28w, https:\/\/ew-nutrition.com\/wp-content\/uploads\/articles\/e.coli-shutterstock_133011722-757x539.jpg 757w\" sizes=\"(max-width: 1200px) 100vw, 1200px\" \/><\/p>\n<\/div>\n<div style=\"text-align: justify;\">\n<h1>Was sind Endotoxine?<\/h1>\n<h2>Herkunft<\/h2>\n<p>Endotoxine wie auch Exotoxine sind bakterielle Toxine. Im Gegensatz zu Exotoxinen, die von lebenden Bakterien aktiv ausgeschieden werden, sind Endotoxine (\u201eEndotoxin\u201c kommt aus dem Griechischen; Endo = Innen; Toxin = Gift) Bestandteile der \u00e4u\u00dferen Zellmembran von gramnegativen Bakterien wie Escherichia coli, Salmonella, Shigella, und Cyanobakterien (Blaualgen). Sie werden nur freigegeben im Falle von<\/p>\n<ul>\n<li>bakteriellem Tod aufgrund eines wirksamen Abwehrmechanismus des Wirts oder der Wirkung bestimmter Antibiotika<\/li>\n<li>Bakterienwachstum (Ausscheidung) (Todar, 2008-2012)<\/li>\n<\/ul>\n<p><img decoding=\"async\" class=\"aligncenter wp-image-61830 size-full\" src=\"https:\/\/ew-nutrition.com\/wp-content\/uploads\/original.jpg\" alt=\"Gram- bacteria\" width=\"720\" height=\"540\" srcset=\"https:\/\/ew-nutrition.com\/wp-content\/uploads\/original.jpg 720w, https:\/\/ew-nutrition.com\/wp-content\/uploads\/original-300x225.jpg 300w, https:\/\/ew-nutrition.com\/wp-content\/uploads\/original-150x113.jpg 150w, https:\/\/ew-nutrition.com\/wp-content\/uploads\/original-120x90.jpg 120w, https:\/\/ew-nutrition.com\/wp-content\/uploads\/original-36x27.jpg 36w, https:\/\/ew-nutrition.com\/wp-content\/uploads\/original-225x169.jpg 225w, https:\/\/ew-nutrition.com\/wp-content\/uploads\/original-80x60.jpg 80w, https:\/\/ew-nutrition.com\/wp-content\/uploads\/original-48x36.jpg 48w, https:\/\/ew-nutrition.com\/wp-content\/uploads\/original-64x48.jpg 64w, https:\/\/ew-nutrition.com\/wp-content\/uploads\/original-28x21.jpg 28w\" sizes=\"(max-width: 720px) 100vw, 720px\" \/><\/p>\n<p>&nbsp;<\/p>\n<p style=\"text-align: center;\"><span style=\"font-size: 10pt;\"><em>\u00a0Das Vorkommen der Endotoxine innerhalb der Bakterienzelle \u00a9 Prof. Dr. med. Marina A. Freudenberg\u00a0\u00a0<\/em><\/span><\/p>\n<\/div>\n<h2>Struktur<\/h2>\n<p>Biochemisch geh\u00f6ren Endotoxine zu den Lipopolysacchariden (LPS). Sie bestehen aus einer relativ einheitlichen Lipidfraktion (Lipid A) und einer speziesspezifischen Polysaccharidkette. Ihre Toxizit\u00e4t ist haupts\u00e4chlich auf das Lipid A zur\u00fcckzuf\u00fchren. Der Polysaccharidteil ist verantwortlich f\u00fcr ihre Aktivit\u00e4t. Im Gegensatz zu den Bakterien sind ihre Endotoxine sehr hitzebest\u00e4ndig und halten einer Sterilisation stand. Die Namen Endotoxin und Lipopolysaccharide werden synonym verwendet, wobei bei &#8220;Endotoxin&#8221; das Augenmerk auf dem Vorkommen und der biologischen Aktivit\u00e4t liegt, bei &#8220;Lipopolysaccharid&#8221; mehr die chemische Struktur hervorgehoben wird (Hurley, 1995).<\/p>\n<p>&nbsp;<\/p>\n<h2>Auswirkungen<\/h2>\n<p>Endotoxine geh\u00f6ren zu den fiebererzeugenden Substanzen. Sie aktivieren die Signalwege mehrerer immunkompetenter Zellen. Ein fr\u00fcher Kontakt mit Endotoxinen f\u00fchrt zur Aktivierung und Reifung des erworbenen Immunsystems. Braun-Fahrl\u00e4nder und Mitarbeiter (2002) stellten fest, dass Kinder, die mit Endotoxinen in Ber\u00fchrung kamen, weniger Probleme mit Heuschnupfen, atopischem Asthma und atopischer Sensibilisierung hatten. Dies passt zusammen mit der Tatsache, dass in menschlichen Populationen nach Erh\u00f6hung der Hygienestandards eine Zunahme von Allergien beobachtet werden konnte.<\/p>\n<p>Verschiedene Tierarten zeigen unterschiedliche Empfindlichkeiten gegen\u00fcber Endotoxininfusionen, z. B. (gesunde) Hunde, Ratten, M\u00e4use, H\u00fchner tolerieren Konzentrationen \u2265 1 mg \/ kg K\u00f6rpergewicht, w\u00e4hrend (gesunde) Wiederk\u00e4uer, Schweine und Pferde bereits bei Konzentrationen &lt;5 \u03bcg\/kg K\u00f6rpergewicht sehr empfindlich reagieren (Olson et al., 1995, zitiert in Wilken, 2003).<\/p>\n<h2>Wann ist ein Organismus einer h\u00f6heren Belastung mit Endotoxinen ausgesetzt?<\/h2>\n<p>Endotoxine kommen nat\u00fcrlicherweise im Darm vor, da die Mikroflora auch gramnegative Bakterien enth\u00e4lt. Sie richten erst Schaden an, wenn sie in den Blutkreislauf gelangen. Solange der Endotoxinspiegel niedrig ist, kann das Immunsystem damit zurechtkommen, h\u00f6here Konzentrationen k\u00f6nnen jedoch kritisch werden. Ein Anstieg der Endotoxine im Organismus resultiert aus einem h\u00f6heren Input und \/ oder einer geringeren Clearance- bzw. Entgiftungsrate.<\/p>\n<h3>Wie kommen mehr Endotoxine in den Organismus<\/h3>\n<p>\u201eNormale\u201c, geringe Mengen an Endotoxinen, die aufgrund regelm\u00e4\u00dfiger bakterieller Aktivit\u00e4t im Darm entstehen und in den Organismus \u00fcbertragen werden, haben keine negativen Auswirkungen, solange die Leber ihre Clearance-Funktion erf\u00fcllt. Auch die im Fettgewebe gespeicherten Endotoxine sind unproblematisch. Einige Faktoren k\u00f6nnen jedoch zu einer Freisetzung der Endotoxine oder deren Translokation in den Organismus f\u00fchren:<\/p>\n<ol>\n<li>\n<h4>Stress<\/h4>\n<\/li>\n<\/ol>\n<p>Stresssituationen wie Geburt, Operationen, Verletzungen k\u00f6nnen zu einer Isch\u00e4mie (mangenlde Blutversorgung) im Darm und zur \u00dcbertragung von Endotoxinen in den Organismus f\u00fchren (Kr\u00fcger, 1997). Andere Stresssituationen in der Tierproduktion, wie <a href=\"https:\/\/ew-nutrition.com\/heat-stress-in-poultry\/\">hohe Temperaturen<\/a> und hohe Besatzdichten, tragen auch zu h\u00f6heren Endotoxinspiegeln im Blutkreislauf bei: Stress f\u00fchrt zu einem h\u00f6heren Stoffwechselbedarf an Wasser, Natrium und energiereichen Substanzen. F\u00fcr eine h\u00f6here Verf\u00fcgbarkeit dieser Substanzen wird die Permeabilit\u00e4t der Darmbarriere erh\u00f6ht, was m\u00f6glicherweise auch zu einer h\u00f6heren Translokation von Bakterien und ihren Toxinen in den Blutkreislauf f\u00fchrt.<\/p>\n<p>Beispiele:<\/p>\n<ul>\n<li>In einer experimentellen Studie von Seidler (1998) (zitiert in Wilken (2003)) wurden h\u00f6here Endotoxinwerte bei Schweinen festgestellt, die unter Stress aufgrund von Belastung, Transport und damit verbundenen erh\u00f6hten Temperaturen litten.<\/li>\n<li>Marathonl\u00e4ufer (Brock-Utne et al., 1988) und Rennpferde (Baker et al., 1988) zeigten ebenfalls h\u00f6here Endotoxinkonzentrationen im Blut proportional zum Laufstress. Dabei liegen bei trainierten Pferden die Konzentrationen niedriger als bei nicht trainierten.<\/li>\n<\/ul>\n<ol start=\"2\">\n<li>\n<h4>Abbau von K\u00f6rperfett zur Energiemobilisierung<\/h4>\n<\/li>\n<\/ol>\n<p>Wenn Endotoxine aufgrund von anhaltendem Stress st\u00e4ndig in den Blutkreislauf gelangen, k\u00f6nnen sie im Fettgewebe gespeichert werden. Der SR-B1 (Scavenger-Rezeptor B1, ein Membranrezeptor, der zur Gruppe der Mustererkennungsrezeptoren (pattern-recognition receptor &#8211; PRR) geh\u00f6rt) bindet sowohl an Lipide als auch an Lipopolysaccharide und f\u00f6rdert damit wahrscheinlich den Einbau von LPS in Chylomikronen. Von Chylomikronen auf andere Lipoproteine \u00fcbertragen, gelangt LPS schlie\u00dflich ins Fettgewebe (Hersoug et al., 2016). Die Mobilisierung von Energie durch Fettabbau, z. B. zu Beginn der Laktation, f\u00fchrt beispielsweise zu einer Wiedereinspeisung von Endotoxinen in den Blutkreislauf.<\/p>\n<ol start=\"3\">\n<li>\n<h4>Besch\u00e4digung der Darmbarriere<\/h4>\n<\/li>\n<\/ol>\n<p>Wie bereits beschrieben, sind Endotoxine aufgrund bakterieller Aktivit\u00e4t unter normalen Bedingungen im Darm vorhanden. Eine Besch\u00e4digung der Darmbarriere erm\u00f6glicht dementsprechend den \u00dcbergang von Endotoxinen (und Bakterien) in den Blutkreislauf<\/p>\n<ol start=\"4\">\n<li>\n<h4>Zerst\u00f6rung von gramnegativen Bakterien<\/h4>\n<\/li>\n<\/ol>\n<p>Eine weitere \u201eQuelle\u201c f\u00fcr Endotoxine ist die Zerst\u00f6rung der Bakterien. Dies kann zum einen durch das Immunsystem des Organismus oder durch die Behandlung mit bakteriziden Substanzen gegen gramnegative Bakterien erfolgen (Kastner, 2002). Um eine erh\u00f6hte Freisetzung von Endotoxinen zu verhindern, sollten dementsprechend gramnegative Bakterien mit bakteriostatischen Substanzen, die nur das Wachstum hemmen und die Bakterien nicht zerst\u00f6ren, oder mit bakteriziden Substanzen in Kombination mit LPS-Bindemitteln behandelt werden (Brandenburg, 2014).<\/p>\n<ol start=\"5\">\n<li>\n<h4>Vermehrung von gramnegativen Bakterien<\/h4>\n<\/li>\n<\/ol>\n<p>Da gramnegative Bakterien auch beim Wachstum geringe Mengen an Endotoxinen freisetzen, f\u00fchrt alles, was ihre Proliferation f\u00f6rdert, auch zu einem Anstieg der Endotoxine:<\/p>\n<p><strong>Ungleichgewicht in der F\u00fctterung<\/strong><\/p>\n<p>Hochleistungsk\u00fche z. B. erhalten f\u00fcr die Milchproduktion Futter mit hohen Gehalten an St\u00e4rke, Fett und Eiwei\u00df. Hohe Gehalte an Kohlenhydraten f\u00fchren zu einem Anstieg von gramnegativen Bakterien. Gleichzeitig f\u00fchrt aber diese F\u00fctterung auch zu einer Absenkung des pH (Azidose), was dann zur Abt\u00f6tung von gramnegativen Bakterien und damit zur Freisetzung von Endotoxinen f\u00fchren kann. Futter mit hohen Fettgehalten f\u00fchrt zu einer h\u00f6heren Konzentration von Endotoxinen im Organismus, da derselbe \u201eTransporter\u201c (Scavenger-Rezeptor Klasse B Typ 1, SR-BI) f\u00fcr die Absorption von Fett (Hersoug et al., 2016) aber von Endotoxinen verwendet werden kann.<\/p>\n<p>In einer Studie von Deopurkar et al. (2010) mit Menschen als Vertretern der Monogastrier wurden gesunden Teilnehmern drei verschiedene Getr\u00e4nke (Glukose &#8211; 100% Kohlenhydrate, Orangensaft &#8211; 92% Kohlenhydrate und Sahne &#8211; 100% Fett) zum Trinken gegeben. Nur das Sahnegetr\u00e4nk erh\u00f6hte den Gehalt an Lipopolysacchariden im Plasma.<\/p>\n<p><strong>Infektionskrankheiten<\/strong><\/p>\n<p>Infektionskrankheiten wie Mastitis, Metritis und andere Infektionen, die durch gramnegative Bakterien wie E. coli, Salmonellen usw. verursacht werden, k\u00f6nnen als Ursache f\u00fcr die Freisetzung von Endotoxinen angesehen werden<\/p>\n<p><strong>Eingeschr\u00e4nkte Entgiftung, verminderter Abbau<\/strong><\/p>\n<p>Hauptverantwortliches Organ: die Leber<\/p>\n<p>Aufgabe: Entgiftung und Abbau von in den Blutkreislauf gelangtem Endotoxin. Die Leber produziert Substanzen wie Lipopolysaccharid-Bindungsproteine (LBP), die zur Bindung und Neutralisierung von Lipopolysaccharid-Strukturen notwendig sind.<\/p>\n<p>W\u00e4hrend der postpartalen Periode befindet sich der Organismus in einer katabolen Phase, mit einem erh\u00f6hten Fettabbau versucht der Organismus, den hohen Energiebedarf f\u00fcr die Milchproduktion zu decken. Eine gesteigerte Lipolyse f\u00fchrt, wie bereits erw\u00e4hnt, zu einer Freisetzung von Endotoxinen aus dem Fettgewebe, aber auch zu einer Verfettung der Leber. Eine verfettete und damit degenerierte Leber kann bei der Endotoxin-Clearance nicht die gleiche Leistung erbringen wie eine normale (Andersen, 2003; Andersen et al., 1996; Harte et al., 2010; Wilken, 2003). \u00a0In einer Studie von Andersen et al. (1996) konnte bei K\u00fchen mit Fettleber keine vollst\u00e4ndige Elimination der Endotoxine erreicht werden. Das Auftreten einer Fettleber nimmt nach der Geburt zu (Reid und Roberts, 1993; Wilken, 2003).<\/p>\n<p>Auch andere Erkrankungen der Leber beeinflussen die Endotoxin-Clearance in der Leber. Hanslin et al. (2019) fanden eine beeintr\u00e4chtigte Endotoxin-Elimination bei Schweinen mit schon bestehendem,\u00a0 systemischem inflammatorischem Response-Syndrom (SIRS).<\/p>\n<h1>Probleme durch Endotoxine<\/h1>\n<p>Endotoxine in geringer Konzentration k\u00f6nnen das Immunsystem positiv stimulieren (Sampath, 2018). Nach McAleer und Vella (2008) werden Lipopolysaccharide als nat\u00fcrliche Adjuvantien verwendet, um bei einer Impfung die Immunreaktion durch Beeinflussung der CD4+T-Zellantwort zu st\u00e4rken. Problematisch an Endotoxinen ist ihre Beteiligung an der Entwicklung schwerwiegender Probleme wie des MMA-Komplexes (Pig Progress) oder eines septischen Schocks (Sampath, 2018).<\/p>\n<h2>MMA-Komplex bei Sauen<\/h2>\n<p>MMA bei Sauen ist eine multifaktorielle Erkrankung, die kurz (12 Stunden bis drei Tage) nach dem Abferkeln auftritt und durch verschiedene Faktoren (Krankheitserreger wie E. coli, Klebsiella spp., Staph. Spp. und Mycoplasma spp., aber auch Stress, Ern\u00e4hrung) verursacht werden kann. MMA ist auch als puerperales Syndrom, puerperale Septik\u00e4mie, Milchfieber oder Tox\u00e4mie bekannt. Die letzte Bezeichnung legt nahe, dass einer der Faktoren, die die Krankheit mit verursachen, bakterielle Endotoxine sind. W\u00e4hrend der perinatalen Phase findet zur Unterst\u00fctzung der Laktation ein massiver Fettabbau statt. Die Sauen leiden h\u00e4ufig unter Verstopfung. Dies kann zu einer h\u00f6heren Durchl\u00e4ssigkeit der Darmwand und zu einer \u00dcbertragung von Bakterien bzw. Endotoxinen in den Blutkreislauf f\u00fchren. Eine weitere \u201eQuelle\u201c f\u00fcr Endotoxine kann das Euter sein, da gramnegative Bakterien in erh\u00f6htem Ma\u00dfe in den Brustdr\u00fcsen vorkommen (Morkoc et al., 1983).<\/p>\n<p>Die Endotoxine k\u00f6nnen zu einer endokrinen Dysfunktion f\u00fchren: \u2191 Cortisol, \u2193 PGF2\u03b1, \u2193 Prolactin, \u2193 Oxytocin. MMA steht f\u00fcr:<\/p>\n<p><strong>Mastitis, eine bakterielle Infektion des Euters<\/strong><\/p>\n<p>Mastitis kann von zwei Seiten provoziert werden: Einerseits f\u00fchrt Endotox\u00e4mie zu einer Erh\u00f6hung der Zytokine (IL1, 6, TNF\u03b1). Niedrigere Ca- und K-Spiegel f\u00fchren dazu, dass der Zitzenschlie\u00dfmuskel weniger funktionsf\u00e4hig ist, was den Eintritt von Umweltpathogenen ins Euter erleichtert und zu Mastitis f\u00fchrt. Andererseits steigt die Cortisolkonzentration als Reaktion auf den Abferkelstress. Die resultierende Immunsuppression erm\u00f6glicht es E. coli, sich im Euter zu vermehren.<\/p>\n<p><strong>Metritis, eine Infektion der Geb\u00e4rmutter mit Ausfluss im Vulvabereich<\/strong><\/p>\n<p>Die Geb\u00e4rmutterentz\u00fcndung f\u00fchrt zu reduzierten Kontraktionen und damit zu einem sich l\u00e4nger hinziehenden und\/oder komplizierten Abferkeln oder zu toten Ferkeln. Stress und die damit verbundene Abnahme der Oxytocin- und Prostaglandin-F2\u03b1-Sekretion kann eine Infektion der Geb\u00e4rmutter f\u00f6rdern. Morkoc et al. (1983) fanden keinen Zusammenhang zwischen Metritis und Endotoxinen.<\/p>\n<p><strong>Agalaktie, eine verringerte oder komplett fehlende Milchproduktion<\/strong><\/p>\n<p>In vielen F\u00e4llen wird eine Agalaktie erst erkannt, wenn die Saugferkel Anzeichen von Hunger und \/ oder Gewichtsverlust zeigen. Im schlimmsten Fall steigt die Sterblichkeitsrate bei den Ferkeln. Wahrscheinlich wird ein Milchmangel durch zu niedrigere Konzentrationen der an der Laktation beteiligten Hormone verursacht. Der Prolaktinspiegel kann z. B. schon durch geringe Mengen an Endotoxin dramatisch gesenkt werden (Smith und Wagner, 1984). Der Oxytocinspiegel ist oft nur halb so hoch wie bei normalen Sauen (Pig Progress, 2020).<\/p>\n<h3>Endotoxinschock<\/h3>\n<p>Ein septischer Schock kann die Reaktion auf die Freisetzung einer hohen Menge an Endotoxinen sein.<\/p>\n<p>Im Falle einer Infektion mit gramnegativen Bakterien werden die Tiere mit (oft bakteriziden) Antibiotika behandelt. Au\u00dferdem findet eine Eliminierung der Bakterien durch das Immunsystem statt. Durch das Absterben vieler Bakterien werden Endotoxine massiv freigesetzt. Im ungebundenen Zustand aktivieren sie das Immunsystem, einschlie\u00dflich Makrophagen, Monozyten und Endothelzellen. Das f\u00fchrt zur Freisetzung gro\u00dfer Mengen an zellul\u00e4ren Mediatoren wie TNF\u03b1, Interleukin 1 (IL-1), IL-6 und Leukotrienen. Hohe Mengen an proinflammatorischen Zytokinen aktivieren die Komplement- und Gerinnungskaskade. Bei einigen Tieren wird dann die Produktion von Prostaglandinen und Leukotrienen stimuliert. Hohes Fieber, verringerter Blutdruck, Bildung von Thromben im Blut, Kollaps, Sch\u00e4digung mehrerer Organe und t\u00f6dlicher (endotoxischer) Schock sind die Folge.<\/p>\n<p>Ein endotoxischer Schock tritt nur bei wenigen anf\u00e4lligen Tieren auf, obwohl die gesamte Herde m\u00f6glicherweise immunstimuliert wurde. Ein weit gr\u00f6\u00dferes Problem stellt der Leistungsabfall der \u00fcbrigen Ferkel dar: Aufgrund der Endotox\u00e4mie wird Energie anstatt f\u00fcr Wachstum f\u00fcr die Immunabwehr eingesetzt.<\/p>\n<h3>Verst\u00e4rkter Durchfall<\/h3>\n<p>Lipopolysaccharide f\u00fchren zu einer erh\u00f6hten Freisetzung von Prostaglandinen, die die Magen-Darm-Funktionen beeinflussen. Zusammen mit Leukotrienen und entz\u00fcndungsf\u00f6rdernden Mediatoren in der Schleimhaut verringern sie die Darmabsorption (Munck et al., 1988; Chiossone et al., 1990), l\u00f6sen aber auch einen pro-sekretorischen Zustand im Darm aus. Liang et al. (2005) beobachteten eine dosisabh\u00e4ngige Ansammlung von reichlich Fl\u00fcssigkeit im D\u00fcnndarm, die bei Ratten zu einer erh\u00f6htem Durchfall und einer verminderten Darmperistaltik f\u00fchrte.<\/p>\n<h4><strong>Fazit<\/strong><\/h4>\n<p>Ma\u00dfnahmen gegen gramnegative Bakterien k\u00f6nnen zu einem noch schwerwiegenderen Problem f\u00fchren &#8211; der Endotox\u00e4mie. Endotoxine wirken sich nicht nur direkt negativ auf den Organismus aus, sie f\u00f6rdern auch die Entwicklung einiger Krankheiten. Die Unterst\u00fctzung der Darmgesundheit durch verschiedene Ans\u00e4tze, einschlie\u00dflich der Bindung von <a href=\"https:\/\/ew-nutrition.com\/all-products\/\">Toxinen<\/a>, tr\u00e4gt dazu bei, Tiere gesund zu erhalten.<\/p>\n<p>&nbsp;<\/p>\n<p><strong>By Inge Heinzl, EW Nutrition<\/strong><\/p>\n<h4>References<\/h4>\n<p>Andersen, P.H. \u201cBovine endotoxicosis \u2013 some aspects of relevance to production diseases. A review.\u201d <em>Acta vet. scand<\/em>. Suppl. 98 (2003): 141-155. DOI: 10.1186\/1751-0147-44-S1-P57<\/p>\n<p>Andersen, P.H., N. Jarl\u00f8v, M. Hesselholt, and L. B\u00e6k. \u201cStudies on in vivo Endotoxin Plasma Disappearance Times in Cattle.\u201d <em>Zentralblatt f\u00fcr Veterin\u00e4rmedizin<\/em>. Reihe A 43 no. 2(1996): 93-101. DOI: 10.1111\/j.1439-0442.1996.tb00432.x<\/p>\n<p>Baker, B., S.L. Gaffin, M. Wells, B.C. Wessels and J.G. Brock-Utne. \u201cEndotoxaemia in racehorses following exertion.\u201d <em>Journal of the South African Veterinary Association<\/em> June (1988): 63-66. https:\/\/journals.co.za\/docserver\/fulltext\/savet\/59\/2\/1341.pdf?expires=1598542211&amp;id=id&amp;accname=guest&amp;checksum=E50C766D318776E09CA41DA912F14CAD<\/p>\n<p>Beutler, B. and T. Rietschel. \u201cInnate immune sensing and its roots: The story of endotoxin.\u201d <em>Nature Reviews \/ Immunology<\/em> 3(2003): 169-176. DOI: 10.1038\/nri1004<\/p>\n<p>Brandenburg, K. \u201cKleines Molek\u00fcl \u2013 gro\u00dfe Hoffnung &#8211; Neue Behandlungsm\u00f6glichkeit gegen Blutvergiftung in Sicht.\u201c Newsletter 70 (Okt.); Bundesministerium f\u00fcr Bildung und Forschung (2014). <a href=\"https:\/\/www.gesundheitsforschung-bmbf.de\/de\/kleines-molekul-grosse-hoffnung-neue-behandlungsmoglichkeit-gegen-blutvergiftung-in-sicht-2716.php\">https:\/\/www.gesundheitsforschung-bmbf.de\/de\/kleines-molekul-grosse-hoffnung-neue-behandlungsmoglichkeit-gegen-blutvergiftung-in-sicht-2716.php<\/a><\/p>\n<p>Braun-Fahrl\u00e4nder, C., J. Riedler, U. Herz, W. Eder, M. Waser, L. Grize, S. Maisch, D. Carr, F. Gerlach, A. Bufe, R.P. Lauener, R. Schierl, H. Renz, D. Nowak and E. von Mutius. \u201eEnvironmental exposure to endotoxin and its relation to asthma in school-age children. \u201d<em>The New England Journal of Medicine <\/em>347 (2002): 869-877. DOI: 10.1056\/NEJMoa020057.<\/p>\n<p>Brock-Utne, J.G., S.L. Gaffin, M.T. Wells, P. Gathiram, E. Sohar, M.F. James, D.F. Morrel, and. R.J. Norman. \u201cEndotoxemia in exhausted runners after a long-distance race.\u201d <em>South Afr. Med. J.<\/em> 73 (1988): 533-536. <a href=\"https:\/\/www.researchgate.net\/publication\/19780279_Endotoxaemia_in_exhausted_runners_after_a_long-distance_race\">https:\/\/www.researchgate.net\/publication\/19780279_Endotoxaemia_in_exhausted_runners_after_a_long-distance_race<\/a><\/p>\n<p>Chiossone, D. C., P.L. Simon, P.L. Smith. \u201cInterleukin-1: effects on rabbit ileal mucosal ion transport in vitro.\u201d <em>European Journal of Pharmacology<\/em> 180 no. 2-3 (1990): 217\u2013228. DOI: 10.1016\/0014-2999(90)90305-P.<\/p>\n<p>Deopurkar R., H. Ghanim, J. Friedman, et al. \u201cDifferential effects of cream, glucose, and orange juice on inflammation, endotoxin, and the expression of Toll-like receptor-4 and suppressor of cytokine signaling-3.\u201d <em>Diabetes care <\/em>33 no. 5 (2010):991\u2013997.<\/p>\n<p>Erridge, C., E. Bennett-Guerrero, and I.R. Poxton. \u201cStructure and function of lipopolysaccharides.\u201d <em>Microbes and Infection<\/em> 4 no. 8 (2002): 837-851. DOI: 10.1016\/s1286-4579(02)01604-0<\/p>\n<p>Fritsche, D. \u201cEndotoxinpromovierte bakterielle Translokationen und Besiedelung von Uterus und Euter beim Hochleistungsrind im peripartalen Zeitraum.\u201c Dissertation. Leipzig, Univ., Veterin\u00e4rmed. Fak. (1998)<\/p>\n<p>Hanslin, K., J. Sj\u00f6lin, P. Skorup, F. Wilske, R. Frithiof, A. Larsson, M. Castegren, E. Tano, and M. Lipcsey. \u201cThe impact of the systemic inflammatory response on hepatic bacterial elimination in experimental abdominal sepsis.\u201d Intensive Care Medicine Experimental 7 (2019): art. 52. <a href=\"https:\/\/doi.org\/10.1186\/s40635-019-0266-x\">https:\/\/doi.org\/10.1186\/s40635-019-0266-x<\/a><\/p>\n<p>Harte, A.L., N.F. da Silva, S.J. Creely, K.C. McGee, T. Billyard, E.M. Youssef-Elabd, G. Tripathi, E. Ashour, M.S. Abdalla, H.M. Sharada, A.I. Amin, A.D. Burt, S. Kumar, C.P. Day and P.G. McTernan. \u201cResearch Elevated endotoxin levels in non-alcoholic fatty liver disease.\u201d <em>Journal of Inflammation<\/em> \u00a07 (2010): 15-24. DOI: 10.1186\/1476-9255-7-15<\/p>\n<p>Hersoug, L.-G., P. M\u00f8ller, and S. Loft. \u201cGut microbiota-derived lipopolysaccharide uptake and trafficking to adipose tissue: implications for inflammation and obesity.\u201d Obesity Reviews 17 (2016): 297\u2013312. DOI: 10.1111\/obr.12370<\/p>\n<p>Hurley, J. C. \u201cEndotoxemia: Methods of detection and clinical correlates.\u201d <em>Clin. Microbiol. Rev<\/em>. 8 (1995): 268\u2013292. DOI: 10.1128\/CMR.8.2.268<\/p>\n<p>Kastner, A. \u201cUntersuchungen zum Fettstoffwechsel und Endotoxin-Metabolismus bei Milchk\u00fchen vor dem Auftreten der Dislocatio abomasi.\u201c Inaug. Diss. Universit\u00e4t Leipzig, Veterin\u00e4rmed. Fak. (2002). <a href=\"https:\/\/d-nb.info\/967451647\/34\">https:\/\/d-nb.info\/967451647\/34<\/a><\/p>\n<p>Kr\u00fcger M. \u201cEscherichia coli: Problemkeim in der Nutztierhaltung.\u201c Darmflora in Symbiose und Pathogenit\u00e4t. \u00d6kologische, physiologische und therapeutische Aspekte von Escherichia coli. 3. Interdisziplin\u00e4res Symposium. Alfred-Nissle-Gesellschaft (Ed.). Ansbach, 28.-29. Nov. (1997): 109-115.<\/p>\n<p>Liang, Y.-C., H.-J. Liu, S.-H. Chen, C.-C. Chen, L.-S. Chou, and L. H. Tsai. \u201c Effect of lipopolysaccharide on diarrhea and gastrointestinal transit in mice: Roles of nitric oxide and prostaglandin E2.\u201d <em>World J Gastroenterol.<\/em> 11 no. 3 (2005): 357\u2013361. DOI: 10.3748\/wjg.v11.i3.357<\/p>\n<p>McAleer, J.P. and Vella, A.T. \u201cUnderstanding how lipopolysaccharide impacts CD4 T cell immunity.\u201d <em>Crit. Rev. Immunol. <\/em>28 no. 4 (2008): 281-299. DOI:10.1615\/CRITREVIMMUNOL.V28.I4.20<\/p>\n<p>Morkok, A., L. Backstrom, L. Lund, A.R.Smith. \u201cBacterial endotoxin in blood of dysgalactic sows in relation to microbial status of uterus, milk, and intestine.\u201d JAVMA 183 (1983): 786-789. PMID: 6629987<\/p>\n<p>Munck, L.K., A. Mertz-Nielsen, H. Westh, K. Buxhave, E. Beubler, J. Rask-Madsen. \u201cProstaglandin E2 is a mediator of 5-hydroxytryptamine induced water and electrolyte secretion in the human jejunum.\u201d <em>Gut<\/em> 29 no. 10 (1988): 1337-1341<\/p>\n<p>Pig Progress. \u201cMastitis, Metritis, Agalactia (MMA).\u201d <a href=\"https:\/\/www.pigprogress.net\/Health\/Health-Tool\/diseases\/Mastitis-metritis-agalactia-MMA\/\">https:\/\/www.pigprogress.net\/Health\/Health-Tool\/diseases\/Mastitis-metritis-agalactia-MMA\/<\/a><\/p>\n<p>Sampath, V.P. \u201cBacterial endotoxin-lipopolysaccharide; structure, function and its role in immunity in vertebrates and invertebrates.\u201d <em>Agriculture and Natural Resources<\/em> 52 no. 2 (2018): 115-120. <a href=\"https:\/\/doi.org\/10.1016\/j.anres.2018.08.002\">https:\/\/doi.org\/10.1016\/j.anres.2018.08.002<\/a><\/p>\n<p>Seidler, T. \u201cFreies Endotoxin in der Blutzirkulation von Schlachtschweinen: eine Ursache f\u00fcr bakterielle Translokationen?\u201c Diss. Universit\u00e4t Leipzig, Veterin\u00e4rmed. Fak. (1998).<\/p>\n<p>Smith, B.B. and W.C. Wagner. \u201cSuppression of prolactin in pigs by Escherichia coli endotoxin.\u201c Science 224 no. 4649 (1984): 605-607<\/p>\n<p>Wilken, H. \u201cEndotoxin-Status und antioxidative Kapazit\u00e4t sowie ausgew\u00e4hlte Stoffwechselparameter bei gesunden Milch- und Mutterk\u00fchen.\u201c Inaugural Diss. Universit\u00e4t Leipzig (2003).<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Erfahren Sie hier mehr \u00fcber Endotoxine Machen Stresssituationen Ihre Tiere krank oder verschlimmert sich eine Krankheit nach Antibiotikabehandlung? Endotoxine k\u00f6nnten die Ursache sein! Was sind Endotoxine? Herkunft Endotoxine wie auch Exotoxine sind bakterielle Toxine. Im Gegensatz zu Exotoxinen, die von lebenden Bakterien aktiv ausgeschieden werden, sind Endotoxine (\u201eEndotoxin\u201c kommt aus dem Griechischen; Endo = Innen;&#8230;<\/p>\n","protected":false},"author":5,"featured_media":55579,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[8075,8127,8076,8121,8077],"tags":[9039,9040],"class_list":["post-61829","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-geflugel","category-mastersorb-de","category-schweine","category-toxine","category-wiederkauer","tag-geflugel","tag-schweine"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v26.5 (Yoast SEO v28.0) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Stehen Endotoxine hinter Ihrer geringen Tierproduktivit\u00e4t? - EW Nutrition<\/title>\n<meta name=\"description\" content=\"Endotoxins can cause impaired animal health in stressful situations or an aggravation of the disease after antibiotic treatment.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/ew-nutrition.com\/de\/are-endotoxins-behind-your-low-livestock-productivity\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Stehen Endotoxine hinter Ihrer geringen Tierproduktivit\u00e4t?\" \/>\n<meta property=\"og:description\" content=\"Endotoxins can cause impaired animal health in stressful situations or an aggravation of the disease after antibiotic treatment.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/ew-nutrition.com\/de\/are-endotoxins-behind-your-low-livestock-productivity\/\" \/>\n<meta property=\"og:site_name\" content=\"EW Nutrition\" \/>\n<meta property=\"article:published_time\" content=\"2020-12-14T07:02:31+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2022-09-20T07:22:19+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/ew-nutrition.com\/wp-content\/uploads\/articles\/downward-graph-orange.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1433\" \/>\n\t<meta property=\"og:image:height\" content=\"1144\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"EW Nutrition\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@EWNutritionGmbH\" \/>\n<meta name=\"twitter:site\" content=\"@EWNutritionGmbH\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"EW Nutrition\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"12 minutes\" \/>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Stehen Endotoxine hinter Ihrer geringen Tierproduktivit\u00e4t? - EW Nutrition","description":"Endotoxins can cause impaired animal health in stressful situations or an aggravation of the disease after antibiotic treatment.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/ew-nutrition.com\/de\/are-endotoxins-behind-your-low-livestock-productivity\/","og_locale":"de_DE","og_type":"article","og_title":"Stehen Endotoxine hinter Ihrer geringen Tierproduktivit\u00e4t?","og_description":"Endotoxins can cause impaired animal health in stressful situations or an aggravation of the disease after antibiotic treatment.","og_url":"https:\/\/ew-nutrition.com\/de\/are-endotoxins-behind-your-low-livestock-productivity\/","og_site_name":"EW Nutrition","article_published_time":"2020-12-14T07:02:31+00:00","article_modified_time":"2022-09-20T07:22:19+00:00","og_image":[{"width":1433,"height":1144,"url":"https:\/\/ew-nutrition.com\/wp-content\/uploads\/articles\/downward-graph-orange.png","type":"image\/png"}],"author":"EW Nutrition","twitter_card":"summary_large_image","twitter_creator":"@EWNutritionGmbH","twitter_site":"@EWNutritionGmbH","twitter_misc":{"Written by":"EW Nutrition","Est. reading time":"12 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/ew-nutrition.com\/de\/are-endotoxins-behind-your-low-livestock-productivity\/#article","isPartOf":{"@id":"https:\/\/ew-nutrition.com\/de\/are-endotoxins-behind-your-low-livestock-productivity\/"},"author":{"name":"EW Nutrition","@id":"https:\/\/ew-nutrition.com\/#\/schema\/person\/4981d28f02cbbf22246e72ffe5066659"},"headline":"Stehen Endotoxine hinter Ihrer geringen Tierproduktivit\u00e4t?","datePublished":"2020-12-14T07:02:31+00:00","dateModified":"2022-09-20T07:22:19+00:00","mainEntityOfPage":{"@id":"https:\/\/ew-nutrition.com\/de\/are-endotoxins-behind-your-low-livestock-productivity\/"},"wordCount":2810,"publisher":{"@id":"https:\/\/ew-nutrition.com\/#organization"},"image":{"@id":"https:\/\/ew-nutrition.com\/de\/are-endotoxins-behind-your-low-livestock-productivity\/#primaryimage"},"thumbnailUrl":"https:\/\/ew-nutrition.com\/wp-content\/uploads\/articles\/downward-graph-orange.png","keywords":["Gefl\u00fcgel","Schweine"],"articleSection":["Gefl\u00fcgel","Mastersorb","Schweine","Toxine","Wiederk\u00e4uer"],"inLanguage":"de"},{"@type":"WebPage","@id":"https:\/\/ew-nutrition.com\/de\/are-endotoxins-behind-your-low-livestock-productivity\/","url":"https:\/\/ew-nutrition.com\/de\/are-endotoxins-behind-your-low-livestock-productivity\/","name":"Stehen Endotoxine hinter Ihrer geringen Tierproduktivit\u00e4t? - EW Nutrition","isPartOf":{"@id":"https:\/\/ew-nutrition.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/ew-nutrition.com\/de\/are-endotoxins-behind-your-low-livestock-productivity\/#primaryimage"},"image":{"@id":"https:\/\/ew-nutrition.com\/de\/are-endotoxins-behind-your-low-livestock-productivity\/#primaryimage"},"thumbnailUrl":"https:\/\/ew-nutrition.com\/wp-content\/uploads\/articles\/downward-graph-orange.png","datePublished":"2020-12-14T07:02:31+00:00","dateModified":"2022-09-20T07:22:19+00:00","description":"Endotoxins can cause impaired animal health in stressful situations or an aggravation of the disease after antibiotic treatment.","breadcrumb":{"@id":"https:\/\/ew-nutrition.com\/de\/are-endotoxins-behind-your-low-livestock-productivity\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/ew-nutrition.com\/de\/are-endotoxins-behind-your-low-livestock-productivity\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/ew-nutrition.com\/de\/are-endotoxins-behind-your-low-livestock-productivity\/#primaryimage","url":"https:\/\/ew-nutrition.com\/wp-content\/uploads\/articles\/downward-graph-orange.png","contentUrl":"https:\/\/ew-nutrition.com\/wp-content\/uploads\/articles\/downward-graph-orange.png","width":1433,"height":1144,"caption":"downward graph orange"},{"@type":"BreadcrumbList","@id":"https:\/\/ew-nutrition.com\/de\/are-endotoxins-behind-your-low-livestock-productivity\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/ew-nutrition.com\/de\/"},{"@type":"ListItem","position":2,"name":"Stehen Endotoxine hinter Ihrer geringen Tierproduktivit\u00e4t?"}]},{"@type":"WebSite","@id":"https:\/\/ew-nutrition.com\/#website","url":"https:\/\/ew-nutrition.com\/","name":"EW Nutrition","description":"Functional Innovations backed by Science","publisher":{"@id":"https:\/\/ew-nutrition.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/ew-nutrition.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/ew-nutrition.com\/#organization","name":"EW Nutrition GmbH","url":"https:\/\/ew-nutrition.com\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/ew-nutrition.com\/#\/schema\/logo\/image\/","url":"","contentUrl":"","caption":"EW Nutrition GmbH"},"image":{"@id":"https:\/\/ew-nutrition.com\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/x.com\/EWNutritionGmbH","https:\/\/www.instagram.com\/ewnutrition\/","https:\/\/www.linkedin.com\/company\/ew-nutrition","https:\/\/www.youtube.com\/channel\/UCIvcb19uSOJXrUecTY8n_dA"]},{"@type":"Person","@id":"https:\/\/ew-nutrition.com\/#\/schema\/person\/4981d28f02cbbf22246e72ffe5066659","name":"EW Nutrition","url":"https:\/\/ew-nutrition.com\/de\/author\/ewnutrition\/"}]}},"_links":{"self":[{"href":"https:\/\/ew-nutrition.com\/de\/wp-json\/wp\/v2\/posts\/61829","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ew-nutrition.com\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ew-nutrition.com\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ew-nutrition.com\/de\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/ew-nutrition.com\/de\/wp-json\/wp\/v2\/comments?post=61829"}],"version-history":[{"count":0,"href":"https:\/\/ew-nutrition.com\/de\/wp-json\/wp\/v2\/posts\/61829\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/ew-nutrition.com\/de\/wp-json\/wp\/v2\/media\/55579"}],"wp:attachment":[{"href":"https:\/\/ew-nutrition.com\/de\/wp-json\/wp\/v2\/media?parent=61829"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ew-nutrition.com\/de\/wp-json\/wp\/v2\/categories?post=61829"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ew-nutrition.com\/de\/wp-json\/wp\/v2\/tags?post=61829"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}